{"id":13573,"date":"2024-02-08T13:47:42","date_gmt":"2024-02-08T12:47:42","guid":{"rendered":"https:\/\/bachhuber-hoteleinrichtungen.de\/service-packages\/"},"modified":"2024-10-27T17:25:53","modified_gmt":"2024-10-27T16:25:53","slug":"service-packages","status":"publish","type":"page","link":"https:\/\/bachhuber-hoteleinrichtungen.de\/en\/service-packages\/","title":{"rendered":"SERVICE PACKAGES"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"13573\" class=\"elementor elementor-13573 elementor-4698\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7945041 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7945041\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ea51a4f\" data-id=\"ea51a4f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be01bec elementor-widget elementor-widget-spacer\" data-id=\"be01bec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e9361f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7e9361f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ac96a46 wgl-add-background-text elementor-section-boxed elementor-section-height-default elementor-section-height-default wgl-animation-background-text\" data-id=\"ac96a46\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-44c3ba8\" data-id=\"44c3ba8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6318b87 elementor-widget elementor-widget-spacer\" data-id=\"6318b87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c92d873 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c92d873\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3139faa\" data-id=\"3139faa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-07293c0\" data-id=\"07293c0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1df32b8 elementor-widget elementor-widget-text-editor\" data-id=\"1df32b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"flex flex-grow flex-col max-w-full\">\n<div class=\"min-h-[20px] text-message flex flex-col items-start gap-3 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\" data-message-author-role=\"assistant\" data-message-id=\"80d5d9bf-5d67-43e4-aa83-58167dc38f85\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<p>As a general contractor, we offer individual service packages for all furnishing and equipment areas.<br \/>\nThe basis for this is provided by interior design concepts, a detailed basic survey, defined DIN standards and official requirements.<br \/>\nYou will receive differentiated implementation descriptions of the respective trades for the selected services.<br \/>\nThese also serve as a quotation and thus ensure transparency and clarity with regard to specific costs.   <\/p>\n<p>In addition to classic fit-out services, you can also choose pure service packages such as consulting or interior design.  <br \/>With a team of experienced experts, cross-industry partnerships and a pool of international interior designers, we have unique know-how.  <\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7aee220\" data-id=\"7aee220\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ab899d3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ab899d3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ef02b95\" data-id=\"ef02b95\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10b6966 elementor-widget elementor-widget-spacer\" data-id=\"10b6966\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-522fc99 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"522fc99\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-89a21a2\" data-id=\"89a21a2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12c170a elementor-widget elementor-widget-image\" data-id=\"12c170a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"284\" height=\"284\" src=\"https:\/\/bachhuber-hoteleinrichtungen.de\/wp-content\/uploads\/2024\/04\/Leistungspaket_1.png\" class=\"attachment-large size-large wp-image-12632\" alt=\"\" srcset=\"https:\/\/bachhuber-hoteleinrichtungen.de\/wp-content\/uploads\/2024\/04\/Leistungspaket_1.png 284w, https:\/\/bachhuber-hoteleinrichtungen.de\/wp-content\/uploads\/2024\/04\/Leistungspaket_1-150x150.png 150w, https:\/\/bachhuber-hoteleinrichtungen.de\/wp-content\/uploads\/2024\/04\/Leistungspaket_1-180x180.png 180w, https:\/\/bachhuber-hoteleinrichtungen.de\/wp-content\/uploads\/2024\/04\/Leistungspaket_1-120x120.png 120w\" sizes=\"(max-width: 284px) 100vw, 284px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9915f9f elementor-widget elementor-widget-text-editor\" data-id=\"9915f9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span>  The <strong>basic furniture package<\/strong> &#8211; ideal for renovations and new furnishings on a small or large scale<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1a92e5 elementor-widget elementor-widget-wgl-toggle-accordion\" data-id=\"b1a92e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wgl-toggle-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"wgl-accordion icon-def\" id=\"wgl-accordion-b1a92e5\" data-type=\"accordion\">\r\n\r\n                            <div class=\"wgl-accordion_panel\">\r\n                    <h1 id=\"wgl-accordion_header-1861\" class=\"wgl-accordion_header\" data-default=\"no\">\r\n                        <span class=\"wgl-accordion_title\">BASE<\/span>\r\n                        <i class=\"wgl-accordion_icon \"><\/i>                    <\/h1>\r\n                    <div class=\"wgl-accordion_content\"><ul>\n<li>Built-in furniture<\/li>\n<li>Loose furniture<\/li>\n<\/ul>\n<\/div>\r\n                <\/div>\r\n            \r\n        <\/div>\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-43fe4bc\" data-id=\"43fe4bc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f53e6d5 elementor-widget elementor-widget-image\" data-id=\"f53e6d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"285\" height=\"284\" src=\"https:\/\/bachhuber-hoteleinrichtungen.de\/wp-content\/uploads\/2024\/04\/Leistungspaket_2.png\" class=\"attachment-large size-large wp-image-12633\" alt=\"\" srcset=\"https:\/\/bachhuber-hoteleinrichtungen.de\/wp-content\/uploads\/2024\/04\/Leistungspaket_2.png 285w, https:\/\/bachhuber-hoteleinrichtungen.de\/wp-content\/uploads\/2024\/04\/Leistungspaket_2-150x150.png 150w, https:\/\/bachhuber-hoteleinrichtungen.de\/wp-content\/uploads\/2024\/04\/Leistungspaket_2-180x180.png 180w, https:\/\/bachhuber-hoteleinrichtungen.de\/wp-content\/uploads\/2024\/04\/Leistungspaket_2-120x120.png 120w\" sizes=\"(max-width: 285px) 100vw, 285px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6fe055b elementor-widget elementor-widget-text-editor\" data-id=\"6fe055b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span>The <strong>basic furniture plus package<\/strong> &#8211; the extended package for complete interior design<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1df27b5 elementor-widget elementor-widget-wgl-toggle-accordion\" data-id=\"1df27b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wgl-toggle-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"wgl-accordion icon-def\" id=\"wgl-accordion-1df27b5\" data-type=\"accordion\">\r\n\r\n                            <div class=\"wgl-accordion_panel\">\r\n                    <h1 id=\"wgl-accordion_header-3141\" class=\"wgl-accordion_header\" data-default=\"no\">\r\n                        <span class=\"wgl-accordion_title\">BASE | FFE<\/span>\r\n                        <i class=\"wgl-accordion_icon \"><\/i>                    <\/h1>\r\n                    <div class=\"wgl-accordion_content\"><ul>\n<li>Built-in furniture<\/li>\n<li>Loose furniture<\/li>\n<li>decorative lights<\/li>\n<li>Decoration (curtains)<\/li>\n<li>techn.<br \/>\nappliances (minibar) <\/li>\n<\/ul>\n<\/div>\r\n                <\/div>\r\n            \r\n        <\/div>\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6c68919 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6c68919\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c808b76\" data-id=\"c808b76\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2974816 elementor-widget elementor-widget-spacer\" data-id=\"2974816\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c872b84 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c872b84\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-18635d1\" data-id=\"18635d1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-523fe45 elementor-widget elementor-widget-image\" data-id=\"523fe45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"285\" height=\"284\" src=\"https:\/\/bachhuber-hoteleinrichtungen.de\/wp-content\/uploads\/2024\/04\/Leistungspaket_3.png\" class=\"attachment-large size-large wp-image-12634\" alt=\"\" srcset=\"https:\/\/bachhuber-hoteleinrichtungen.de\/wp-content\/uploads\/2024\/04\/Leistungspaket_3.png 285w, https:\/\/bachhuber-hoteleinrichtungen.de\/wp-content\/uploads\/2024\/04\/Leistungspaket_3-150x150.png 150w, https:\/\/bachhuber-hoteleinrichtungen.de\/wp-content\/uploads\/2024\/04\/Leistungspaket_3-180x180.png 180w, https:\/\/bachhuber-hoteleinrichtungen.de\/wp-content\/uploads\/2024\/04\/Leistungspaket_3-120x120.png 120w\" sizes=\"(max-width: 285px) 100vw, 285px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b253f41 elementor-widget elementor-widget-text-editor\" data-id=\"b253f41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span>The <strong>basic room package<\/strong> &#8211; the complete furnishing including the room extension &#8211; GU<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cdc55cc elementor-widget elementor-widget-wgl-toggle-accordion\" data-id=\"cdc55cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wgl-toggle-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"wgl-accordion icon-def\" id=\"wgl-accordion-cdc55cc\" data-type=\"accordion\">\r\n\r\n                            <div class=\"wgl-accordion_panel\">\r\n                    <h1 id=\"wgl-accordion_header-2151\" class=\"wgl-accordion_header\" data-default=\"no\">\r\n                        <span class=\"wgl-accordion_title\">BASE | FFE | Turn Key | CT<\/span>\r\n                        <i class=\"wgl-accordion_icon \"><\/i>                    <\/h1>\r\n                    <div class=\"wgl-accordion_content\"><ul>\n<li>Built-in furniture<\/li>\n<li>Loose furniture<\/li>\n<li>decorative lights<\/li>\n<li>Decoration (curtains)<\/li>\n<li>techn.<br \/>\nappliances (minibar) <\/li>\n<li>Cooling technology<\/li>\n<li>Floor coverings (carpet, wood and stone floors)<\/li>\n<li>Plasterboard work<\/li>\n<li>Doors<\/li>\n<li>Painting work<\/li>\n<li>Bathrooms (from angle valve)<\/li>\n<li>Tiles\/sealing<\/li>\n<li>Washbasin<\/li>\n<li>Accessories<\/li>\n<li>Sanitary items<\/li>\n<li>Basic lighting<\/li>\n<\/ul>\n<\/div>\r\n                <\/div>\r\n            \r\n        <\/div>\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-cf8f27f\" data-id=\"cf8f27f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d3738a elementor-widget elementor-widget-image\" data-id=\"5d3738a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"284\" height=\"284\" src=\"https:\/\/bachhuber-hoteleinrichtungen.de\/wp-content\/uploads\/2024\/04\/Leistungspaket_4.png\" class=\"attachment-large size-large wp-image-12635\" alt=\"\" srcset=\"https:\/\/bachhuber-hoteleinrichtungen.de\/wp-content\/uploads\/2024\/04\/Leistungspaket_4.png 284w, https:\/\/bachhuber-hoteleinrichtungen.de\/wp-content\/uploads\/2024\/04\/Leistungspaket_4-150x150.png 150w, https:\/\/bachhuber-hoteleinrichtungen.de\/wp-content\/uploads\/2024\/04\/Leistungspaket_4-180x180.png 180w, https:\/\/bachhuber-hoteleinrichtungen.de\/wp-content\/uploads\/2024\/04\/Leistungspaket_4-120x120.png 120w\" sizes=\"(max-width: 284px) 100vw, 284px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d92268 elementor-widget elementor-widget-text-editor\" data-id=\"3d92268\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span>  The<strong> complete room plus package<\/strong> &#8211; basic room package Total fit-out including building services<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d6e2be elementor-widget elementor-widget-wgl-toggle-accordion\" data-id=\"3d6e2be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wgl-toggle-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"wgl-accordion icon-def\" id=\"wgl-accordion-3d6e2be\" data-type=\"accordion\">\r\n\r\n                            <div class=\"wgl-accordion_panel\">\r\n                    <h1 id=\"wgl-accordion_header-6441\" class=\"wgl-accordion_header\" data-default=\"no\">\r\n                        <span class=\"wgl-accordion_title\">BASE | FFE | Turn Key | CT | OS E | Kitchen<\/span>\r\n                        <i class=\"wgl-accordion_icon \"><\/i>                    <\/h1>\r\n                    <div class=\"wgl-accordion_content\"><p>Like package 3 but<\/p>\n<ul>\n<li>OS &amp; E<\/li>\n<li>IT<\/li>\n<li>Kitchen<\/li>\n<li>Electric ventilation<\/li>\n<\/ul>\n<\/div>\r\n                <\/div>\r\n            \r\n        <\/div>\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a3d4208 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a3d4208\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1fb1450\" data-id=\"1fb1450\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d33acad elementor-widget elementor-widget-spacer\" data-id=\"d33acad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-daf795a acenter elementor-widget elementor-widget-wgl-double-headings\" data-id=\"daf795a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wgl-double-headings.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wgl-double_heading\">                <h2 class=\"dbl-title_wrapper\"><span class=\"dbl-title dbl-title_1\">Optional:<\/span> <span class=\"dbl-title dbl-title_2\">  Can be booked individually - or optionally added to any of the packages 1 - 4  <\/span>                 <\/h2>        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d670d93 elementor-widget elementor-widget-spacer\" data-id=\"d670d93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-313ef81 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"313ef81\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e7ca46e\" data-id=\"e7ca46e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-04d79dd elementor-widget elementor-widget-image\" data-id=\"04d79dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"284\" height=\"284\" src=\"https:\/\/bachhuber-hoteleinrichtungen.de\/wp-content\/uploads\/2024\/04\/Leistungspaket_5.png\" class=\"attachment-large size-large wp-image-12636\" alt=\"\" srcset=\"https:\/\/bachhuber-hoteleinrichtungen.de\/wp-content\/uploads\/2024\/04\/Leistungspaket_5.png 284w, https:\/\/bachhuber-hoteleinrichtungen.de\/wp-content\/uploads\/2024\/04\/Leistungspaket_5-150x150.png 150w, https:\/\/bachhuber-hoteleinrichtungen.de\/wp-content\/uploads\/2024\/04\/Leistungspaket_5-180x180.png 180w, https:\/\/bachhuber-hoteleinrichtungen.de\/wp-content\/uploads\/2024\/04\/Leistungspaket_5-120x120.png 120w\" sizes=\"(max-width: 284px) 100vw, 284px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1aa1d39 elementor-widget elementor-widget-text-editor\" data-id=\"1aa1d39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"\">\n<div class=\"WordSection1\">\n<div class=\"\"><span class=\"\"><strong>Advice<\/strong> on all aspects of your property, <strong>processing<\/strong> and <strong>operational procedures<\/strong> (our experience and expertise from over 60 years in the industry are incorporated here)<\/span><\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e140738 elementor-widget elementor-widget-wgl-toggle-accordion\" data-id=\"e140738\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wgl-toggle-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"wgl-accordion icon-def\" id=\"wgl-accordion-e140738\" data-type=\"accordion\">\r\n\r\n                            <div class=\"wgl-accordion_panel\">\r\n                    <h1 id=\"wgl-accordion_header-2361\" class=\"wgl-accordion_header\" data-default=\"no\">\r\n                        <span class=\"wgl-accordion_title\">CONSULTING<\/span>\r\n                        <i class=\"wgl-accordion_icon \"><\/i>                    <\/h1>\r\n                    <div class=\"wgl-accordion_content\"><ul>\n<li>Room programs<\/li>\n<li>Building and furnishing standards<\/li>\n<li>Planning advice<\/li>\n<li>Determination and delimitation of investment costs<\/li>\n<li>Concept development<\/li>\n<li>Strategic consulting<\/li>\n<li>Project management, controlling and TA\/TSA<\/li>\n<\/ul>\n<\/div>\r\n                <\/div>\r\n            \r\n        <\/div>\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a7c3310\" data-id=\"a7c3310\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f90b1e elementor-widget elementor-widget-image\" data-id=\"7f90b1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"284\" height=\"284\" src=\"https:\/\/bachhuber-hoteleinrichtungen.de\/wp-content\/uploads\/2024\/04\/Leistungspaket_5.png\" class=\"attachment-large size-large wp-image-12636\" alt=\"\" srcset=\"https:\/\/bachhuber-hoteleinrichtungen.de\/wp-content\/uploads\/2024\/04\/Leistungspaket_5.png 284w, https:\/\/bachhuber-hoteleinrichtungen.de\/wp-content\/uploads\/2024\/04\/Leistungspaket_5-150x150.png 150w, https:\/\/bachhuber-hoteleinrichtungen.de\/wp-content\/uploads\/2024\/04\/Leistungspaket_5-180x180.png 180w, https:\/\/bachhuber-hoteleinrichtungen.de\/wp-content\/uploads\/2024\/04\/Leistungspaket_5-120x120.png 120w\" sizes=\"(max-width: 284px) 100vw, 284px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d162a72 elementor-widget elementor-widget-text-editor\" data-id=\"d162a72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"\">\n<div class=\"WordSection1\">\n<div class=\"\"><span class=\"\"><strong>All service phases<\/strong> from concept development \/ design planning, implementation planning, works planning to construction supervision<\/span><\/div>\n<div> <\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1e2f6e elementor-widget elementor-widget-wgl-toggle-accordion\" data-id=\"e1e2f6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wgl-toggle-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"wgl-accordion icon-def\" id=\"wgl-accordion-e1e2f6e\" data-type=\"accordion\">\r\n\r\n                            <div class=\"wgl-accordion_panel\">\r\n                    <h1 id=\"wgl-accordion_header-2361\" class=\"wgl-accordion_header\" data-default=\"no\">\r\n                        <span class=\"wgl-accordion_title\">INTERIOR ARCHITECTURE<\/span>\r\n                        <i class=\"wgl-accordion_icon \"><\/i>                    <\/h1>\r\n                    <div class=\"wgl-accordion_content\"><ul>\n<li>Concept<\/li>\n<li>Design planning<\/li>\n<li>Implementation planning<\/li>\n<li>Material selection<\/li>\n<li>Visualizations<\/li>\n<li>Construction supervision<\/li>\n<li>Decoration<\/li>\n<\/ul>\n<\/div>\r\n                <\/div>\r\n            \r\n        <\/div>\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-79fa17e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"79fa17e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fb57894\" data-id=\"fb57894\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7cfb57f elementor-widget elementor-widget-spacer\" data-id=\"7cfb57f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-28b0396 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"28b0396\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-686f978\" data-id=\"686f978\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-08011dc elementor-widget elementor-widget-text-editor\" data-id=\"08011dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"flex flex-grow flex-col max-w-full\">\n<div class=\"min-h-[20px] text-message flex flex-col items-start gap-3 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\" data-message-author-role=\"assistant\" data-message-id=\"80d5d9bf-5d67-43e4-aa83-58167dc38f85\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<p>If one of the service packages meets your requirements or if you would like more information, please contact us by e-mail or telephone. We will be happy to help you realize your project. <\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b54246e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b54246e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8c7b0f3\" data-id=\"8c7b0f3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d0d750 elementor-widget elementor-widget-spacer\" data-id=\"0d0d750\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b7af2e5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b7af2e5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e691b2f\" data-id=\"e691b2f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fcf8f8c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"fcf8f8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>As a general contractor, we offer individual service packages for all furnishing and equipment areas. The basis for this is provided by interior design concepts, a detailed basic survey, defined DIN standards and official requirements. You will receive differentiated implementation descriptions of the respective trades for the selected services. These also serve as a quotation [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-13573","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Als Generalunternehmer bieten wir individuelle Leistungspakete f\u00fcr alle Einrichtungs- und Ausstattungsbereiche. Als Grundlage daf\u00fcr dienen innenarchitektonische Konzepte.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"T_1MFU7NeKR3j1_WGLiH0ngTpCXv83NeAHg5GwbP8uQ\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/bachhuber-hoteleinrichtungen.de\/en\/service-packages\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Bachhuber - Architekt Hotel \u2013 und Gastronomieeinrichtungen Schreinerei\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Wir planen und bauen Hotels | Bachhuber Contract GmbH &amp; Co KG\" \/>\n\t\t<meta property=\"og:description\" content=\"Als Generalunternehmer bieten wir individuelle Leistungspakete f\u00fcr alle Einrichtungs- und Ausstattungsbereiche. Als Grundlage daf\u00fcr dienen innenarchitektonische Konzepte.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/bachhuber-hoteleinrichtungen.de\/en\/service-packages\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-02-08T12:47:42+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-10-27T16:25:53+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Wir planen und bauen Hotels | Bachhuber Contract GmbH &amp; Co KG\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Als Generalunternehmer bieten wir individuelle Leistungspakete f\u00fcr alle Einrichtungs- und Ausstattungsbereiche. Als Grundlage daf\u00fcr dienen innenarchitektonische Konzepte.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bachhuber-hoteleinrichtungen.de\\\/en\\\/service-packages\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bachhuber-hoteleinrichtungen.de\\\/en\\\/#listItem\",\"position\":1,\"name\":\"Zu Hause\",\"item\":\"https:\\\/\\\/bachhuber-hoteleinrichtungen.de\\\/en\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bachhuber-hoteleinrichtungen.de\\\/en\\\/service-packages\\\/#listItem\",\"name\":\"SERVICE PACKAGES\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bachhuber-hoteleinrichtungen.de\\\/en\\\/service-packages\\\/#listItem\",\"position\":2,\"name\":\"SERVICE PACKAGES\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bachhuber-hoteleinrichtungen.de\\\/en\\\/#listItem\",\"name\":\"Zu Hause\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bachhuber-hoteleinrichtungen.de\\\/en\\\/#organization\",\"name\":\"Bachhuber\",\"description\":\"Architekt Hotel \\u2013 und Gastronomieeinrichtungen Schreinerei\",\"url\":\"https:\\\/\\\/bachhuber-hoteleinrichtungen.de\\\/en\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bachhuber-hoteleinrichtungen.de\\\/en\\\/service-packages\\\/#webpage\",\"url\":\"https:\\\/\\\/bachhuber-hoteleinrichtungen.de\\\/en\\\/service-packages\\\/\",\"name\":\"Wir planen und bauen Hotels | Bachhuber Contract GmbH & Co KG\",\"description\":\"Als Generalunternehmer bieten wir individuelle Leistungspakete f\\u00fcr alle Einrichtungs- und Ausstattungsbereiche. Als Grundlage daf\\u00fcr dienen innenarchitektonische Konzepte.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bachhuber-hoteleinrichtungen.de\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bachhuber-hoteleinrichtungen.de\\\/en\\\/service-packages\\\/#breadcrumblist\"},\"datePublished\":\"2024-02-08T13:47:42+01:00\",\"dateModified\":\"2024-10-27T17:25:53+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bachhuber-hoteleinrichtungen.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/bachhuber-hoteleinrichtungen.de\\\/en\\\/\",\"name\":\"Bachhuber\",\"description\":\"Architekt Hotel \\u2013 und Gastronomieeinrichtungen Schreinerei\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/bachhuber-hoteleinrichtungen.de\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Wir planen und bauen Hotels | Bachhuber Contract GmbH & Co KG","description":"Als Generalunternehmer bieten wir individuelle Leistungspakete f\u00fcr alle Einrichtungs- und Ausstattungsbereiche. Als Grundlage daf\u00fcr dienen innenarchitektonische Konzepte.","canonical_url":"https:\/\/bachhuber-hoteleinrichtungen.de\/en\/service-packages\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"T_1MFU7NeKR3j1_WGLiH0ngTpCXv83NeAHg5GwbP8uQ","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/bachhuber-hoteleinrichtungen.de\/en\/service-packages\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/bachhuber-hoteleinrichtungen.de\/en\/#listItem","position":1,"name":"Zu Hause","item":"https:\/\/bachhuber-hoteleinrichtungen.de\/en\/","nextItem":{"@type":"ListItem","@id":"https:\/\/bachhuber-hoteleinrichtungen.de\/en\/service-packages\/#listItem","name":"SERVICE PACKAGES"}},{"@type":"ListItem","@id":"https:\/\/bachhuber-hoteleinrichtungen.de\/en\/service-packages\/#listItem","position":2,"name":"SERVICE PACKAGES","previousItem":{"@type":"ListItem","@id":"https:\/\/bachhuber-hoteleinrichtungen.de\/en\/#listItem","name":"Zu Hause"}}]},{"@type":"Organization","@id":"https:\/\/bachhuber-hoteleinrichtungen.de\/en\/#organization","name":"Bachhuber","description":"Architekt Hotel \u2013 und Gastronomieeinrichtungen Schreinerei","url":"https:\/\/bachhuber-hoteleinrichtungen.de\/en\/"},{"@type":"WebPage","@id":"https:\/\/bachhuber-hoteleinrichtungen.de\/en\/service-packages\/#webpage","url":"https:\/\/bachhuber-hoteleinrichtungen.de\/en\/service-packages\/","name":"Wir planen und bauen Hotels | Bachhuber Contract GmbH & Co KG","description":"Als Generalunternehmer bieten wir individuelle Leistungspakete f\u00fcr alle Einrichtungs- und Ausstattungsbereiche. Als Grundlage daf\u00fcr dienen innenarchitektonische Konzepte.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/bachhuber-hoteleinrichtungen.de\/en\/#website"},"breadcrumb":{"@id":"https:\/\/bachhuber-hoteleinrichtungen.de\/en\/service-packages\/#breadcrumblist"},"datePublished":"2024-02-08T13:47:42+01:00","dateModified":"2024-10-27T17:25:53+01:00"},{"@type":"WebSite","@id":"https:\/\/bachhuber-hoteleinrichtungen.de\/en\/#website","url":"https:\/\/bachhuber-hoteleinrichtungen.de\/en\/","name":"Bachhuber","description":"Architekt Hotel \u2013 und Gastronomieeinrichtungen Schreinerei","inLanguage":"en-US","publisher":{"@id":"https:\/\/bachhuber-hoteleinrichtungen.de\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Bachhuber - Architekt Hotel \u2013 und Gastronomieeinrichtungen Schreinerei","og:type":"article","og:title":"Wir planen und bauen Hotels | Bachhuber Contract GmbH &amp; Co KG","og:description":"Als Generalunternehmer bieten wir individuelle Leistungspakete f\u00fcr alle Einrichtungs- und Ausstattungsbereiche. Als Grundlage daf\u00fcr dienen innenarchitektonische Konzepte.","og:url":"https:\/\/bachhuber-hoteleinrichtungen.de\/en\/service-packages\/","article:published_time":"2024-02-08T12:47:42+00:00","article:modified_time":"2024-10-27T16:25:53+00:00","twitter:card":"summary_large_image","twitter:title":"Wir planen und bauen Hotels | Bachhuber Contract GmbH &amp; Co KG","twitter:description":"Als Generalunternehmer bieten wir individuelle Leistungspakete f\u00fcr alle Einrichtungs- und Ausstattungsbereiche. Als Grundlage daf\u00fcr dienen innenarchitektonische Konzepte."},"aioseo_meta_data":{"post_id":"13573","title":"Wir planen und bauen Hotels | Bachhuber Contract GmbH &amp; Co KG","description":"Als Generalunternehmer bieten wir individuelle Leistungspakete f\u00fcr alle Einrichtungs- und Ausstattungsbereiche. Als Grundlage daf\u00fcr dienen innenarchitektonische Konzepte.","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-08-08 06:24:13","updated":"2025-06-06 07:37:27","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/bachhuber-hoteleinrichtungen.de\/en\/\" title=\"Zu Hause\">Zu Hause<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSERVICE PACKAGES\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Zu Hause","link":"https:\/\/bachhuber-hoteleinrichtungen.de\/en\/"},{"label":"SERVICE PACKAGES","link":"https:\/\/bachhuber-hoteleinrichtungen.de\/en\/service-packages\/"}],"_links":{"self":[{"href":"https:\/\/bachhuber-hoteleinrichtungen.de\/en\/wp-json\/wp\/v2\/pages\/13573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bachhuber-hoteleinrichtungen.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bachhuber-hoteleinrichtungen.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bachhuber-hoteleinrichtungen.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/bachhuber-hoteleinrichtungen.de\/en\/wp-json\/wp\/v2\/comments?post=13573"}],"version-history":[{"count":4,"href":"https:\/\/bachhuber-hoteleinrichtungen.de\/en\/wp-json\/wp\/v2\/pages\/13573\/revisions"}],"predecessor-version":[{"id":14396,"href":"https:\/\/bachhuber-hoteleinrichtungen.de\/en\/wp-json\/wp\/v2\/pages\/13573\/revisions\/14396"}],"wp:attachment":[{"href":"https:\/\/bachhuber-hoteleinrichtungen.de\/en\/wp-json\/wp\/v2\/media?parent=13573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}